{"id":5986,"date":"2019-11-15T10:49:47","date_gmt":"2019-11-15T09:49:47","guid":{"rendered":"https:\/\/www.cmalleida.com\/?p=5986"},"modified":"2019-11-15T10:49:47","modified_gmt":"2019-11-15T09:49:47","slug":"el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo","status":"publish","type":"post","link":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/","title":{"rendered":"El Col\u00b7legi de Mediadors d&#8217;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo"},"content":{"rendered":"<p><em>&#8211; El presidente del Col\u00b7legi Javier Barber\u00e1 y el secretario y responsable de formaci\u00f3n Quim Puyuelo, <\/em><em>forman parte del Cecas como Presidente y miembro de la comisi\u00f3n de valoraci\u00f3n, respectivamente\u00a0<\/em><br \/>\n<em>&#8211; Cambio clim\u00e1tico, cambios demogr\u00e1ficos y cambios en los h\u00e1bitos de consumo, los 3 temas que se <\/em><em>tratan en la jornada<\/em><br \/>\n_________________________________________________________________<\/p>\n<p>El presidente del Col\u00b7legi de Mediadors d\u2019Assegurances de Lleida, sr. Javier Barber\u00e1; los vicepresidentes sra. Esmeralda Caselles y sr. Francesc Farr\u00e9; y el secretario y responsable de formaci\u00f3n, sr. Quim Puyuelo han asistido hoy al XVII F\u00f3rum Cecas, el encuentro nacional de profesionales de mediadores de seguros que se celebra este a\u00f1o en Toledo.<\/p>\n<p>Barber\u00e1 y Puyuelo, adem\u00e1s de formar parte del Col\u00b7legi de Mediadors d\u2019Assegurances de Lleida, son miembros del Cecas como presidente y miembro de la comisi\u00f3n de valoraci\u00f3n, respectivamente<\/p>\n<p>El F\u00f3rum Cecas, bajo el titulo de \u201cParamos el Tiempo para hablar de futuro\u201d, gira entorno a 3 grandes temas y riesgos que el sector asegurador tiene que hacer frente: el cambio clim\u00e1tico, los cambios demogr\u00e1ficos y los cambios en los h\u00e1bitos de consumo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; El presidente del Col\u00b7legi Javier Barber\u00e1 y el secretario y responsable de formaci\u00f3n Quim Puyuelo, forman parte del Cecas como Presidente y miembro de&#8230; <a href=\"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/\" rel=\"nofollow\" class=\"lollegirmes\">Llegeix m\u00e9s<\/a><\/p>\n","protected":false},"author":149,"featured_media":5983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[28,101],"tags":[],"class_list":["post-5986","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-recortes-de-prensa","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"og:description\" content=\"&#8211; El presidente del Col\u00b7legi Javier Barber\u00e1 y el secretario y responsable de formaci\u00f3n Quim Puyuelo, forman parte del Cecas como Presidente y miembro de... Llegeix m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-15T09:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/forum-cecas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonieta Castells Dolcet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonieta Castells Dolcet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/\"},\"author\":{\"name\":\"Antonieta Castells Dolcet\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\"},\"headline\":\"El Col\u00b7legi de Mediadors d&#8217;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo\",\"datePublished\":\"2019-11-15T09:49:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/forum-cecas.jpg\",\"articleSection\":[\"Actualidad\",\"Recopilaciones de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/\",\"name\":\"El Col\u00b7legi de Mediadors d'Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/forum-cecas.jpg\",\"datePublished\":\"2019-11-15T09:49:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/forum-cecas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/forum-cecas.jpg\",\"width\":1024,\"height\":768,\"caption\":\"forum cecas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Col\u00b7legi de Mediadors d&#8217;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"name\":\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\",\"name\":\"Antonieta Castells Dolcet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"caption\":\"Antonieta Castells Dolcet\"},\"sameAs\":[\"http:\\\/\\\/www.cmalleida.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Col\u00b7legi de Mediadors d'Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/","og_locale":"es_ES","og_type":"article","og_title":"El Col\u00b7legi de Mediadors d'Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","og_description":"&#8211; El presidente del Col\u00b7legi Javier Barber\u00e1 y el secretario y responsable de formaci\u00f3n Quim Puyuelo, forman parte del Cecas como Presidente y miembro de... Llegeix m\u00e9s","og_url":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/","og_site_name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","article_published_time":"2019-11-15T09:49:47+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/forum-cecas.jpg","type":"image\/jpeg"}],"author":"Antonieta Castells Dolcet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonieta Castells Dolcet","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#article","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/"},"author":{"name":"Antonieta Castells Dolcet","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4"},"headline":"El Col\u00b7legi de Mediadors d&#8217;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo","datePublished":"2019-11-15T09:49:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/"},"wordCount":213,"publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/forum-cecas.jpg","articleSection":["Actualidad","Recopilaciones de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/","url":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/","name":"El Col\u00b7legi de Mediadors d'Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#primaryimage"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/forum-cecas.jpg","datePublished":"2019-11-15T09:49:47+00:00","breadcrumb":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#primaryimage","url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/forum-cecas.jpg","contentUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/forum-cecas.jpg","width":1024,"height":768,"caption":"forum cecas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-mediadors-dassegurances-de-lleida-presente-en-el-forum-cecas-2019-en-toledo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cmalleida.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Col\u00b7legi de Mediadors d&#8217;Assegurances de Lleida, presente en el F\u00f3rum CECAS 2019 en Toledo"}]},{"@type":"WebSite","@id":"https:\/\/www.cmalleida.com\/es\/#website","url":"https:\/\/www.cmalleida.com\/es\/","name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmalleida.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cmalleida.com\/es\/#organization","name":"Col\u00b7legi de Mediadors d'Assegurances de Lleida","url":"https:\/\/www.cmalleida.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Col\u00b7legi de Mediadors d'Assegurances de Lleida"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4","name":"Antonieta Castells Dolcet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","caption":"Antonieta Castells Dolcet"},"sameAs":["http:\/\/www.cmalleida.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/5986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/comments?post=5986"}],"version-history":[{"count":1,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/5986\/revisions"}],"predecessor-version":[{"id":5987,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/5986\/revisions\/5987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media\/5983"}],"wp:attachment":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media?parent=5986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/categories?post=5986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/tags?post=5986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}