{"id":14499,"date":"2025-06-06T12:38:45","date_gmt":"2025-06-06T10:38:45","guid":{"rendered":"https:\/\/www.cmalleida.com\/?p=14499"},"modified":"2025-06-10T12:32:55","modified_gmt":"2025-06-10T10:32:55","slug":"el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona","status":"publish","type":"post","link":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/","title":{"rendered":"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona"},"content":{"rendered":"<p>El Colegio de Mediadores de Seguros de Lleida celebr\u00f3 ayer por la tarde el D\u00eda del Seguro, la fiesta anual para conmemorar el D\u00eda de la Patrona. El evento, que este a\u00f1o giraba en torno al lema \u00abUna Diada de altura\u00bb, reuni\u00f3 a 150 profesionales de los seguros en una Sala de La Canonja llena.<\/p>\n<p>Sin embargo, antes del acto principal de la Diada, los directores territoriales de las entidades colaboradoras del Colegio pudieron hacer un recorrido exterior por La Seu Vella y descubrir detalles que pueden pasar desapercibidos a simple vista. Posteriormente, descubrieron las curiosidades del claustro de La Seu Vella.<\/p>\n<p>Una vez realizado el recorrido, todos los profesionales se encontraron en la Gran Sala de La Canonja, espacio patrocinado por AXA, donde se dio paso a la bienvenida y al acto, presentado por el periodista leridano Santi Roig. Turisme de Lleida explic\u00f3 a todos los asistentes en qu\u00e9 punto de la ciudad nos encontr\u00e1bamos y qu\u00e9 simbolizaba para los leridanos y leridanas.<\/p>\n<p>Una vez realizada la parte m\u00e1s cultural, se procedi\u00f3 con las entregas de premios, galardones y reconocimientos. Los responsables de Responsabilidad Social Corporativa del Colegio de Lleida, Rosa M. Barrera y Ramon Armengol, entregaron el Cubierto Solidario a C\u00e1ritas Diocesana de Lleida, una aportaci\u00f3n econ\u00f3mica destinada a esta entidad sin \u00e1nimo de lucro que trabaja para una causa social.<\/p>\n<p>Seguidamente, los diez alumnos de la promoci\u00f3n del Curso Nivel I de seguros recibieron su acreditaci\u00f3n en manos del responsable del curso Quim Puyuelo.<\/p>\n<p>El tramo final de la noche se destin\u00f3 a la entrega de premios especiales. Javier Barber\u00e1, presidente del Colegio y Esmeralda Caselles y Francesc Farr\u00e9, vicepresidentes, fueron los encargados de entregar los galardones. Santiago Mons\u00f3 recibi\u00f3 el reconocimiento a 25 a\u00f1os de colegiado; Eduard Segarra recibi\u00f3 la Silla Colegial, un premio destinado a un profesional de los seguros que ha tenido una relaci\u00f3n especial con el Colegio; y finalmente el Premio 231, destinado este a\u00f1o a Allianz por su estrecha vinculaci\u00f3n con el Colegio durante el a\u00f1o.<\/p>\n<p>Poniendo punto y final a la Diada 2025, el presidente del Colegio Javier Barber\u00e1 dirigi\u00f3 unas palabras a los asistentes, donde puso de manifiesto la figura de los profesionales de los seguros en los momentos m\u00e1s inciertos como la DANA de Valencia o los incendios. Tambi\u00e9n se hizo un repaso a toda la actividad colegial durante el 2024 y haciendo \u00e9nfasis en la Diada del a\u00f1o 2026 donde el Colegio celebrar\u00e1 su 60 aniversario.<\/p>\n<p>A continuaci\u00f3n se dio paso al refrigerio en un entorno inmejorable con La Seu Vella como protagonista. En esta edici\u00f3n de la Diada, estuvieron presentes la Sra. Merc\u00e8 Herrera, presidenta del Colegio de Mediadores de Seguros de Girona, el Sr. \u00c0lex Mestre, presidente del Colegio de Mediadores de Seguros de Tarragona y presidente del Consell de Col\u00b7legis de Mediadors d&#8217;Assegurances de Catalunya. As\u00ed como los directores y directoras territoriales de las entidades colaboradoras del Colegio: CASER, EXSEL, FIATC, GENERALI, MUTUACAT, ONLYGAL, PELAYO, PREVISION MALLORQUINA, PREVISORA GENERAL y VITAL SEGURO.<\/p>\n<p><a href=\"https:\/\/app.box.com\/s\/0kvzdsotg2mi5b1rpmc6amfwyp8s9e06\" target=\"_blank\" rel=\"noopener\"><strong>FOTOS<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14496\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/10-1-300x198.jpg\" alt=\"10\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/10-1-300x198.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/10-1-1024x675.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/10-1-768x506.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/10-1-1536x1013.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/10-1-2048x1351.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14494\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/9-1-300x200.jpg\" alt=\"9\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/9-1-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/9-1-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/9-1-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/9-1-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/9-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14492\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/8-300x200.jpg\" alt=\"8\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/8-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/8-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/8-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/8-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/8-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14490\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/7-300x200.jpg\" alt=\"7\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/7-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/7-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/7-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/7-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/7-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14488\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/6-1-300x200.jpg\" alt=\"6\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/6-1-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/6-1-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/6-1-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/6-1-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/6-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14486\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/5-300x200.jpg\" alt=\"5\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/5-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/5-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/5-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/5-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/5-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14484\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/4-1-300x200.jpg\" alt=\"4\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/4-1-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/4-1-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/4-1-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/4-1-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/4-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14482\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/3-2-300x200.jpg\" alt=\"3\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/3-2-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/3-2-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/3-2-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/3-2-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/3-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14480\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/2-3-300x200.jpg\" alt=\"2\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/2-3-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/2-3-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/2-3-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/2-3-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/2-3-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14478\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/1-8-300x200.jpg\" alt=\"1\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/1-8-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/1-8-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/1-8-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/1-8-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/1-8-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14476\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/11-1-300x200.jpg\" alt=\"11\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/11-1-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/11-1-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/11-1-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/11-1-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/11-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14474\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/diada-2025-300x200.jpg\" alt=\"DIADA 2025\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio de Mediadores de Seguros de Lleida celebr\u00f3 ayer por la tarde el D\u00eda del Seguro, la fiesta anual para conmemorar el D\u00eda de&#8230; <a href=\"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/\" rel=\"nofollow\" class=\"lollegirmes\">Llegeix m\u00e9s<\/a><\/p>\n","protected":false},"author":149,"featured_media":14475,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[28,60,101],"tags":[],"class_list":["post-14499","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-noticias-colegiales","category-recortes-de-prensa","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"og:description\" content=\"El Colegio de Mediadores de Seguros de Lleida celebr\u00f3 ayer por la tarde el D\u00eda del Seguro, la fiesta anual para conmemorar el D\u00eda de... Llegeix m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-06T10:38:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T10:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonieta Castells Dolcet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonieta Castells Dolcet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/\"},\"author\":{\"name\":\"Antonieta Castells Dolcet\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\"},\"headline\":\"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona\",\"datePublished\":\"2025-06-06T10:38:45+00:00\",\"dateModified\":\"2025-06-10T10:32:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/\"},\"wordCount\":528,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/diada-2025.jpg\",\"articleSection\":[\"Actualidad\",\"Noticias Colegiales\",\"Recopilaciones de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/\",\"name\":\"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/diada-2025.jpg\",\"datePublished\":\"2025-06-06T10:38:45+00:00\",\"dateModified\":\"2025-06-10T10:32:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/diada-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/diada-2025.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"DIADA 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"name\":\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\",\"name\":\"Antonieta Castells Dolcet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"caption\":\"Antonieta Castells Dolcet\"},\"sameAs\":[\"http:\\\/\\\/www.cmalleida.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/","og_locale":"es_ES","og_type":"article","og_title":"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","og_description":"El Colegio de Mediadores de Seguros de Lleida celebr\u00f3 ayer por la tarde el D\u00eda del Seguro, la fiesta anual para conmemorar el D\u00eda de... Llegeix m\u00e9s","og_url":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/","og_site_name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","article_published_time":"2025-06-06T10:38:45+00:00","article_modified_time":"2025-06-10T10:32:55+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025-1024x683.jpg","type":"image\/jpeg"}],"author":"Antonieta Castells Dolcet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonieta Castells Dolcet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#article","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/"},"author":{"name":"Antonieta Castells Dolcet","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4"},"headline":"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona","datePublished":"2025-06-06T10:38:45+00:00","dateModified":"2025-06-10T10:32:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/"},"wordCount":528,"publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025.jpg","articleSection":["Actualidad","Noticias Colegiales","Recopilaciones de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/","url":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/","name":"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#primaryimage"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025.jpg","datePublished":"2025-06-06T10:38:45+00:00","dateModified":"2025-06-10T10:32:55+00:00","breadcrumb":{"@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#primaryimage","url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025.jpg","contentUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/diada-2025.jpg","width":2560,"height":1707,"caption":"DIADA 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmalleida.com\/es\/el-collegi-de-lleida-celebra-la-diada-de-lasseguranca-festa-de-la-patrona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cmalleida.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Colegio de Lleida celebra el D\u00eda del Seguro, fiesta de la patrona"}]},{"@type":"WebSite","@id":"https:\/\/www.cmalleida.com\/es\/#website","url":"https:\/\/www.cmalleida.com\/es\/","name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmalleida.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cmalleida.com\/es\/#organization","name":"Col\u00b7legi de Mediadors d'Assegurances de Lleida","url":"https:\/\/www.cmalleida.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Col\u00b7legi de Mediadors d'Assegurances de Lleida"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4","name":"Antonieta Castells Dolcet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","caption":"Antonieta Castells Dolcet"},"sameAs":["http:\/\/www.cmalleida.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/14499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/comments?post=14499"}],"version-history":[{"count":7,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/14499\/revisions"}],"predecessor-version":[{"id":14517,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/14499\/revisions\/14517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media\/14475"}],"wp:attachment":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media?parent=14499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/categories?post=14499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/tags?post=14499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}