{"id":14011,"date":"2025-01-24T10:07:55","date_gmt":"2025-01-24T09:07:55","guid":{"rendered":"https:\/\/www.cmalleida.com\/?p=14011"},"modified":"2025-01-29T18:18:52","modified_gmt":"2025-01-29T17:18:52","slug":"javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029","status":"publish","type":"post","link":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/","title":{"rendered":"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14015\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/xavi10-1-300x200.jpg\" alt=\"XAVI10\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi10-1-300x200.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi10-1-1024x683.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi10-1-768x512.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi10-1-1536x1024.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi10-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>23\/1\/2025<\/strong>. El presidente del Colegio de Mediadores de Seguros de Lleida<strong>, Javier Barber\u00e1<\/strong> encabeza la \u00fanica propuesta a la presidencia de los Mediadores tras expirar ayer el plazo legal de presentaci\u00f3n de candidaturas al Consejo General.<\/p>\n<p>Pese a haberse recibido una \u00fanica lista en el plazo fijado por los estatutos, el Consejo General de Mediadores deber\u00e1 celebrar el correspondiente Pleno electoral el pr\u00f3ximo 13 de febrero.<\/p>\n<p>La candidatura encabezada por Javier Barber\u00e1 ha presentado 33 avales que suponen el 78,5% de los Colegios con derecho a voto. El reglamento electoral exige un m\u00ednimo de 10 apoyos para oficializar una candidatura.<\/p>\n<p>La lista completa queda de la siguiente manera:<\/p>\n<p><strong>Presidente<\/strong><\/p>\n<ul>\n<li><strong>Javier Barber\u00e1<\/strong> &#8211; Colegio de Lleida<\/li>\n<\/ul>\n<p><strong>Vicepresidente<\/strong><\/p>\n<ul>\n<li><strong>Rafael Cabello<\/strong> &#8211; Colegio de Sevilla, Huelva y C\u00f3rdoba<\/li>\n<\/ul>\n<p><strong>Tesorero<\/strong><\/p>\n<ul>\n<li><strong>V\u00edctor Carpintero<\/strong> &#8211; Colegio de Cantabria<\/li>\n<\/ul>\n<p><strong>Vocales<\/strong><\/p>\n<ul>\n<li><strong>Mar\u00eda Casta\u00f1eda<\/strong> &#8211; Colegio de Navarra<\/li>\n<li><strong>Miguel de las Morenas<\/strong> &#8211; Colegio de Zaragoza<\/li>\n<li><strong>Zacar\u00edas Fern\u00e1ndez Salgado<\/strong> &#8211; Colegio de Badajoz<\/li>\n<li><strong>Enrique Garc\u00eda M\u00e9rida<\/strong> &#8211; Colegio de Toledo<\/li>\n<li><strong>Mar\u00eda Jos\u00e9 Laguna<\/strong> &#8211; Colegio de Valladolid<\/li>\n<li><strong>Fernando Solsona<\/strong> &#8211; Colegio de Castell\u00f3n<\/li>\n<\/ul>\n<p>De los nueve miembros propuestos para la Comisi\u00f3n Permanente, seis son de nueva incorporaci\u00f3n al \u00f3rgano de Gobierno: Sevilla, Navarra, Cantabria, Valladolid, Toledo y Castell\u00f3n.<\/p>\n<p>Javier Barber\u00e1 fue elegido presidente del Consejo General, en febrero de 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>23\/1\/2025. El presidente del Colegio de Mediadores de Seguros de Lleida, Javier Barber\u00e1 encabeza la \u00fanica propuesta a la presidencia de los Mediadores tras expirar&#8230; <a href=\"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/\" rel=\"nofollow\" class=\"lollegirmes\">Llegeix m\u00e9s<\/a><\/p>\n","protected":false},"author":149,"featured_media":8303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[28,60,101],"tags":[],"class_list":["post-14011","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-noticias-colegiales","category-recortes-de-prensa","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029 - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029 - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"og:description\" content=\"23\/1\/2025. El presidente del Colegio de Mediadores de Seguros de Lleida, Javier Barber\u00e1 encabeza la \u00fanica propuesta a la presidencia de los Mediadores tras expirar... Llegeix m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-24T09:07:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T17:18:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi12-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonieta Castells Dolcet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonieta Castells Dolcet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/\"},\"author\":{\"name\":\"Antonieta Castells Dolcet\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\"},\"headline\":\"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029\",\"datePublished\":\"2025-01-24T09:07:55+00:00\",\"dateModified\":\"2025-01-29T17:18:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/xavi12.jpg\",\"articleSection\":[\"Actualidad\",\"Noticias Colegiales\",\"Recopilaciones de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/\",\"name\":\"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029 - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/xavi12.jpg\",\"datePublished\":\"2025-01-24T09:07:55+00:00\",\"dateModified\":\"2025-01-29T17:18:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/xavi12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/xavi12.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"XAVI12\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"name\":\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\",\"name\":\"Antonieta Castells Dolcet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"caption\":\"Antonieta Castells Dolcet\"},\"sameAs\":[\"http:\\\/\\\/www.cmalleida.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029 - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/","og_locale":"es_ES","og_type":"article","og_title":"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029 - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","og_description":"23\/1\/2025. El presidente del Colegio de Mediadores de Seguros de Lleida, Javier Barber\u00e1 encabeza la \u00fanica propuesta a la presidencia de los Mediadores tras expirar... Llegeix m\u00e9s","og_url":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/","og_site_name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","article_published_time":"2025-01-24T09:07:55+00:00","article_modified_time":"2025-01-29T17:18:52+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi12-1024x683.jpg","type":"image\/jpeg"}],"author":"Antonieta Castells Dolcet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonieta Castells Dolcet","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#article","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/"},"author":{"name":"Antonieta Castells Dolcet","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4"},"headline":"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029","datePublished":"2025-01-24T09:07:55+00:00","dateModified":"2025-01-29T17:18:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/"},"wordCount":235,"publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi12.jpg","articleSection":["Actualidad","Noticias Colegiales","Recopilaciones de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/","url":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/","name":"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029 - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#primaryimage"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi12.jpg","datePublished":"2025-01-24T09:07:55+00:00","dateModified":"2025-01-29T17:18:52+00:00","breadcrumb":{"@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#primaryimage","url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi12.jpg","contentUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/xavi12.jpg","width":2560,"height":1707,"caption":"XAVI12"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmalleida.com\/es\/javier-barbera-encabeza-la-unica-lista-para-presidir-el-consejo-general-de-mediadores-hasta-2029\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cmalleida.com\/es\/"},{"@type":"ListItem","position":2,"name":"Javier Barber\u00e1 encabeza la \u00fanica lista para presidir el Consejo General de Mediadores hasta 2029"}]},{"@type":"WebSite","@id":"https:\/\/www.cmalleida.com\/es\/#website","url":"https:\/\/www.cmalleida.com\/es\/","name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmalleida.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cmalleida.com\/es\/#organization","name":"Col\u00b7legi de Mediadors d'Assegurances de Lleida","url":"https:\/\/www.cmalleida.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Col\u00b7legi de Mediadors d'Assegurances de Lleida"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4","name":"Antonieta Castells Dolcet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","caption":"Antonieta Castells Dolcet"},"sameAs":["http:\/\/www.cmalleida.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/14011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/comments?post=14011"}],"version-history":[{"count":3,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/14011\/revisions"}],"predecessor-version":[{"id":14030,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/14011\/revisions\/14030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media\/8303"}],"wp:attachment":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media?parent=14011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/categories?post=14011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/tags?post=14011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}