{"id":13914,"date":"2024-12-04T17:00:57","date_gmt":"2024-12-04T16:00:57","guid":{"rendered":"https:\/\/www.cmalleida.com\/?p=13914"},"modified":"2024-12-04T17:00:57","modified_gmt":"2024-12-04T16:00:57","slug":"el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza","status":"publish","type":"post","link":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/","title":{"rendered":"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza"},"content":{"rendered":"<p>Renovar acuerdos con entidades aseguradoras refuerza la colaboraci\u00f3n entre \u00e9stas y el Colegio de Lleida para impulsar la mediaci\u00f3n en la regi\u00f3n de Lleida<\/p>\n<p>El Colegio de Mediadores de Seguros de Lleida y Occidente ha firmado un acuerdo de colaboraci\u00f3n que refuerza el compromiso de ambas entidades con la profesionalizaci\u00f3n y desarrollo del sector asegurador. En la firma del convenio han estado presentes Javier Barber\u00e1 Ferr\u00e9, presidente del Colegio de Mediadores de Seguros de Lleida y Miguel Cortegano, director territorial Catalu\u00f1a Arag\u00f3n de Occidente.<\/p>\n<p>Con esta alianza, estrechamos lazos y fomentamos iniciativas conjuntas en beneficio de los mediadores colegiados. Occidente reafirma su compromiso con la mediaci\u00f3n y, en concreto, con los mediadores de la zona de L\u00e9rida, en Catalu\u00f1a. Este compromiso se materializar\u00e1 mediante actividades conjuntas de formaci\u00f3n, divulgaci\u00f3n y networking. Adem\u00e1s, se llevar\u00e1n a cabo acciones espec\u00edficas para apoyar el desarrollo profesional de los mediadores y promover el intercambio de conocimientos.<\/p>\n<p>El acuerdo pone de relieve la apostad ambas partes por la excelencia en el sector asegurador, ofreciendo nuevas oportunidades de desarrollo y colaboraci\u00f3n para los profesionales colegiados.<\/p>\n<p>Javier Barber\u00e1 ha indicado que \u00abla renovaci\u00f3n de este convenio con Occidente representa un paso adelante en nuestro esfuerzo por fortalecer el apoyo a los mediadores colegiados. Esta colaboraci\u00f3n ayudar\u00e1 a fomentar la excelencia en el sector asegurador\u00bb. Por su parte, Miguel Cortegano resalta que \u201cen Occidente, creemos firmemente en el valor de la mediaci\u00f3n como motor del sector asegurador. Este acuerdo nos permite reforzar nuestro compromiso con el desarrollo profesional de los mediadores, promoviendo una colaboraci\u00f3n que beneficia tanto a los colegiados como a los asegurados\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renovar acuerdos con entidades aseguradoras refuerza la colaboraci\u00f3n entre \u00e9stas y el Colegio de Lleida para impulsar la mediaci\u00f3n en la regi\u00f3n de Lleida El&#8230; <a href=\"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/\" rel=\"nofollow\" class=\"lollegirmes\">Llegeix m\u00e9s<\/a><\/p>\n","protected":false},"author":149,"featured_media":13912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[28,60,101],"tags":[],"class_list":["post-13914","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-noticias-colegiales","category-recortes-de-prensa","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"og:description\" content=\"Renovar acuerdos con entidades aseguradoras refuerza la colaboraci\u00f3n entre \u00e9stas y el Colegio de Lleida para impulsar la mediaci\u00f3n en la regi\u00f3n de Lleida El... Llegeix m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T16:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0007-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonieta Castells Dolcet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonieta Castells Dolcet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/\"},\"author\":{\"name\":\"Antonieta Castells Dolcet\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\"},\"headline\":\"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza\",\"datePublished\":\"2024-12-04T16:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/\"},\"wordCount\":299,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0007-16.jpg\",\"articleSection\":[\"Actualidad\",\"Noticias Colegiales\",\"Recopilaciones de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/\",\"name\":\"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0007-16.jpg\",\"datePublished\":\"2024-12-04T16:00:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0007-16.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0007-16.jpg\",\"width\":2560,\"height\":1526,\"caption\":\"DSC_0007\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"name\":\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\",\"name\":\"Antonieta Castells Dolcet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"caption\":\"Antonieta Castells Dolcet\"},\"sameAs\":[\"http:\\\/\\\/www.cmalleida.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/","og_locale":"es_ES","og_type":"article","og_title":"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","og_description":"Renovar acuerdos con entidades aseguradoras refuerza la colaboraci\u00f3n entre \u00e9stas y el Colegio de Lleida para impulsar la mediaci\u00f3n en la regi\u00f3n de Lleida El... Llegeix m\u00e9s","og_url":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/","og_site_name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","article_published_time":"2024-12-04T16:00:57+00:00","og_image":[{"width":2560,"height":1526,"url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0007-16.jpg","type":"image\/jpeg"}],"author":"Antonieta Castells Dolcet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonieta Castells Dolcet","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#article","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/"},"author":{"name":"Antonieta Castells Dolcet","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4"},"headline":"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza","datePublished":"2024-12-04T16:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/"},"wordCount":299,"publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0007-16.jpg","articleSection":["Actualidad","Noticias Colegiales","Recopilaciones de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/","url":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/","name":"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#primaryimage"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0007-16.jpg","datePublished":"2024-12-04T16:00:57+00:00","breadcrumb":{"@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#primaryimage","url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0007-16.jpg","contentUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0007-16.jpg","width":2560,"height":1526,"caption":"DSC_0007"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmalleida.com\/es\/el-colegio-de-mediadores-de-seguros-de-lleida-y-occidente-renovamos-nuestra-alianza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cmalleida.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Colegio de Mediadores de Seguros de Lleida y Occidente renovamos nuestra alianza"}]},{"@type":"WebSite","@id":"https:\/\/www.cmalleida.com\/es\/#website","url":"https:\/\/www.cmalleida.com\/es\/","name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmalleida.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cmalleida.com\/es\/#organization","name":"Col\u00b7legi de Mediadors d'Assegurances de Lleida","url":"https:\/\/www.cmalleida.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Col\u00b7legi de Mediadors d'Assegurances de Lleida"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4","name":"Antonieta Castells Dolcet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","caption":"Antonieta Castells Dolcet"},"sameAs":["http:\/\/www.cmalleida.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/13914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/comments?post=13914"}],"version-history":[{"count":1,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/13914\/revisions"}],"predecessor-version":[{"id":13915,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/13914\/revisions\/13915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media\/13912"}],"wp:attachment":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media?parent=13914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/categories?post=13914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/tags?post=13914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}