{"id":13740,"date":"2024-10-08T12:06:05","date_gmt":"2024-10-08T10:06:05","guid":{"rendered":"https:\/\/www.cmalleida.com\/?p=13740"},"modified":"2024-10-15T17:38:55","modified_gmt":"2024-10-15T15:38:55","slug":"almuerzo-tertulia-con-fiatc","status":"publish","type":"post","link":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/","title":{"rendered":"Almuerzo tert\u00falia con FIATC"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13735\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/dsc-0009-12-300x201.jpg\" alt=\"DSC_0009\" width=\"300\" height=\"201\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0009-12-300x201.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0009-12-1024x684.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0009-12-768x513.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0009-12-1536x1027.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0009-12-2048x1369.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13737\" src=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/\/dsc-0015-4-300x201.jpg\" alt=\"DSC_0015\" width=\"300\" height=\"201\" srcset=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0015-4-300x201.jpg 300w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0015-4-1024x684.jpg 1024w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0015-4-768x513.jpg 768w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0015-4-1536x1027.jpg 1536w, https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0015-4-2048x1369.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>8 de octubre &#8211; El Colegio de Mediadores de Seguros de Lleida celebramos la semana pasada la habitual Dinar Tert\u00falia, esta vez con FIATC como entidad colaboradora invitada. Al encuentro asistieron Joan Castells Trius, presidente ejecutivo; Santiago G\u00f3mez Sanz, director \u00c1rea Comercial y Organizaci\u00f3n territorial; y Anton L\u00f3pez, director de la Territorial L\u00e9rida &#8211; Andorra de FIATC.<\/p>\n<p>En esta XXXVIII comida tertulia asistieron una decena de colegiados que conocieron m\u00e1s de cerca la entidad, la actualidad, los principales servicios&#8230; y tuvieron unos minutos de intercambio de impresiones, experiencias reales del d\u00eda a d\u00eda y oportunidad de realizar preguntas y resolver dudas.<\/p>\n<p>Durante la comida, Joan Castells explic\u00f3 que es FIATC, sus a\u00f1os de historia y el crecimiento que en estos momentos es de un 9,5%. Coment\u00f3 que en 1986 se cre\u00f3 el ramo de salud, en base a la incorporaci\u00f3n de las nuevas oficinas y la cl\u00ednica en la Avenida Diagonal de Barcelona. Tanto el ramo de salud, como el de vida y otros que se crearon fueron muy importantes para compensar el poco crecimiento del ramo de autos, como consecuencia del mal resultado del mismo.<\/p>\n<p>Igualmente dijo que FIATC es una mutua donde la base es el equipo humano, un valor a\u00f1adido que est\u00e1 en alza adem\u00e1s de ser una compa\u00f1\u00eda donde la mediaci\u00f3n tiene un papel fundamental en la distribuci\u00f3n de los distintos seguros. Es una mutua que posee un CRM de clientes y un CRM de mediadores. Finaliz\u00f3 diciendo que Fiatc est\u00e1 en el 19\u00ba lugar del mercado, que es una compa\u00f1\u00eda espa\u00f1ola, catalana y totalmente de mediadores y que lo importante es el trato humano que debemos poner en valor y hacer ver al cliente lo importante de las coberturas.<\/p>\n<p>Santi G\u00f3mez destac\u00f3 expresamente dos de las peculiaridades que distinguen a FIATC que son la proximidad y la coherencia. Cercan\u00eda desde las 46 oficinas propias y su organizaci\u00f3n comercial y t\u00e9cnica, y coherencia en cuanto a la mediaci\u00f3n para que trabajen con todos los canales de distribuci\u00f3n pero con todos a igualdad de condiciones y primas.<\/p>\n<p>Coment\u00f3 que el ramo principal de FIATC, en estos momentos, es el ramo de Vida y despu\u00e9s Salut, entre los dos casi representan el 60% de las primas, autos un 17% y el resto multirriesgos y ramos diversos. Alent\u00f3 a los mediadores asistentes a trabajar con la entidad dado que el cliente de la entidad es el mediador.<\/p>\n<p>Se abri\u00f3 el coloquio donde los asistentes opinaron sobre diferentes aspectos y realizaron varias consultas. Al finalizar el turno abierto de palabras, el presidente del Colegio, <strong>Javier Barber\u00e0<\/strong>, entreg\u00f3 el caracol-corredor a Joan Castells, quien agradeci\u00f3 la invitaci\u00f3n y a los asistentes su participaci\u00f3n.<\/p>\n<p><em>Estos encuentros se inici\u00f3 en 1998 para hablar con el \u201cdirector regional\u201d y el director de la sucursal en Lleida sobre la problem\u00e1tica que puede haber en ciertos asuntos; sobre las perspectivas de la provincia y otros temas de inter\u00e9s para los asistentes. Bajo una normativa donde durante el primer plato no se puede hablar de seguros y durante el segundo se puede hablar de todos e incluso de seguros el Colegio de Lleida lleva ya veintis\u00e9is a\u00f1os (24 si cuentan el paro por la pandemia y otros contratiempos) organizando este evento que estamos convencidos de que servicios para decir a la entidad la situaci\u00f3n actual en la que se encuentran los mediadores; al tener contactos con otros mediadores colegiados y al crear una amena e interesante tertulia.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 de octubre &#8211; El Colegio de Mediadores de Seguros de Lleida celebramos la semana pasada la habitual Dinar Tert\u00falia, esta vez con FIATC como&#8230; <a href=\"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/\" rel=\"nofollow\" class=\"lollegirmes\">Llegeix m\u00e9s<\/a><\/p>\n","protected":false},"author":149,"featured_media":13753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[28,60,101],"tags":[],"class_list":["post-13740","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-noticias-colegiales","category-recortes-de-prensa","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Almuerzo tert\u00falia con FIATC - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Almuerzo tert\u00falia con FIATC - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"og:description\" content=\"8 de octubre &#8211; El Colegio de Mediadores de Seguros de Lleida celebramos la semana pasada la habitual Dinar Tert\u00falia, esta vez con FIATC como... Llegeix m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T10:06:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T15:38:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0022-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2481\" \/>\n\t<meta property=\"og:image:height\" content=\"1903\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonieta Castells Dolcet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonieta Castells Dolcet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/\"},\"author\":{\"name\":\"Antonieta Castells Dolcet\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\"},\"headline\":\"Almuerzo tert\u00falia con FIATC\",\"datePublished\":\"2024-10-08T10:06:05+00:00\",\"dateModified\":\"2024-10-15T15:38:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/\"},\"wordCount\":600,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0022-1.jpg\",\"articleSection\":[\"Actualidad\",\"Noticias Colegiales\",\"Recopilaciones de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/\",\"name\":\"Almuerzo tert\u00falia con FIATC - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0022-1.jpg\",\"datePublished\":\"2024-10-08T10:06:05+00:00\",\"dateModified\":\"2024-10-15T15:38:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0022-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmalleida.com\\\/wp-content\\\/uploads\\\/dsc-0022-1.jpg\",\"width\":2481,\"height\":1903,\"caption\":\"DSC_0022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/almuerzo-tertulia-con-fiatc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Almuerzo tert\u00falia con FIATC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"name\":\"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#organization\",\"name\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\",\"url\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Col\u00b7legi de Mediadors d'Assegurances de Lleida\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cmalleida.com\\\/es\\\/#\\\/schema\\\/person\\\/7461453022a0d6ce41c1e530eb4443b4\",\"name\":\"Antonieta Castells Dolcet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g\",\"caption\":\"Antonieta Castells Dolcet\"},\"sameAs\":[\"http:\\\/\\\/www.cmalleida.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Almuerzo tert\u00falia con FIATC - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/","og_locale":"es_ES","og_type":"article","og_title":"Almuerzo tert\u00falia con FIATC - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","og_description":"8 de octubre &#8211; El Colegio de Mediadores de Seguros de Lleida celebramos la semana pasada la habitual Dinar Tert\u00falia, esta vez con FIATC como... Llegeix m\u00e9s","og_url":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/","og_site_name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","article_published_time":"2024-10-08T10:06:05+00:00","article_modified_time":"2024-10-15T15:38:55+00:00","og_image":[{"width":2481,"height":1903,"url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0022-1.jpg","type":"image\/jpeg"}],"author":"Antonieta Castells Dolcet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonieta Castells Dolcet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#article","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/"},"author":{"name":"Antonieta Castells Dolcet","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4"},"headline":"Almuerzo tert\u00falia con FIATC","datePublished":"2024-10-08T10:06:05+00:00","dateModified":"2024-10-15T15:38:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/"},"wordCount":600,"publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0022-1.jpg","articleSection":["Actualidad","Noticias Colegiales","Recopilaciones de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/","url":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/","name":"Almuerzo tert\u00falia con FIATC - Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","isPartOf":{"@id":"https:\/\/www.cmalleida.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#primaryimage"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0022-1.jpg","datePublished":"2024-10-08T10:06:05+00:00","dateModified":"2024-10-15T15:38:55+00:00","breadcrumb":{"@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#primaryimage","url":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0022-1.jpg","contentUrl":"https:\/\/www.cmalleida.com\/wp-content\/uploads\/dsc-0022-1.jpg","width":2481,"height":1903,"caption":"DSC_0022"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmalleida.com\/es\/almuerzo-tertulia-con-fiatc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cmalleida.com\/es\/"},{"@type":"ListItem","position":2,"name":"Almuerzo tert\u00falia con FIATC"}]},{"@type":"WebSite","@id":"https:\/\/www.cmalleida.com\/es\/#website","url":"https:\/\/www.cmalleida.com\/es\/","name":"Col\u00b7legi de Mediadors d&#039;Assegurances de Lleida","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.cmalleida.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmalleida.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cmalleida.com\/es\/#organization","name":"Col\u00b7legi de Mediadors d'Assegurances de Lleida","url":"https:\/\/www.cmalleida.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Col\u00b7legi de Mediadors d'Assegurances de Lleida"},"image":{"@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cmalleida.com\/es\/#\/schema\/person\/7461453022a0d6ce41c1e530eb4443b4","name":"Antonieta Castells Dolcet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7738df9a8ff2d12e8b37d088ff0e3e36016e57ab29e5db27ba4fb758a81ea3cb?s=96&d=mm&r=g","caption":"Antonieta Castells Dolcet"},"sameAs":["http:\/\/www.cmalleida.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/13740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/comments?post=13740"}],"version-history":[{"count":6,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/13740\/revisions"}],"predecessor-version":[{"id":13772,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/posts\/13740\/revisions\/13772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media\/13753"}],"wp:attachment":[{"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/media?parent=13740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/categories?post=13740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmalleida.com\/es\/wp-json\/wp\/v2\/tags?post=13740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}